{"id":492,"count":1,"description":"","link":"https:\/\/adolescenciaactiva.campana.gov.ar\/index.php\/tag\/desigualdad\/","name":"desigualdad","slug":"desigualdad","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/adolescenciaactiva.campana.gov.ar\/index.php\/wp-json\/wp\/v2\/tags\/492"}],"collection":[{"href":"https:\/\/adolescenciaactiva.campana.gov.ar\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/adolescenciaactiva.campana.gov.ar\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/adolescenciaactiva.campana.gov.ar\/index.php\/wp-json\/wp\/v2\/posts?tags=492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}